{"id":70901,"date":"2025-10-21T11:43:36","date_gmt":"2025-10-21T11:43:36","guid":{"rendered":"https:\/\/altsignals.io\/?p=70901"},"modified":"2025-10-21T16:49:52","modified_gmt":"2025-10-21T16:49:52","slug":"bitget-cartera-integra-actualizacion-eip-7702","status":"publish","type":"post","link":"https:\/\/altsignals.io\/es\/post\/bitget-cartera-integra-actualizacion-eip-7702","title":{"rendered":"La Billetera Bitget Integra EIP-7702 para Permitir el Pago de Tarifas de Transacciones de Red con Stablecoin"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube\">\n  <div class=\"wp-block-embed__wrapper\">\n    <iframe title=\"Bitget Wallet Adopts EIP-7702 for Stablecoin Payment of Network Transaction Fees\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-547xLHQ2UY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n  <\/div>\n<\/figure>\n\n\n<h2>Bitget Wallet Implementa Propuesta de Mejora de Ethereum<\/h2>\n\n<p>En un movimiento pionero, Bitget Wallet, un proveedor l\u00edder de billeteras de criptomonedas, ha lanzado recientemente una actualizaci\u00f3n que integra una Propuesta de Mejora de Ethereum. Esta actualizaci\u00f3n estrat\u00e9gica permite a los usuarios pagar sus tarifas de transacci\u00f3n en la red con stablecoins, ofreciendo una conveniencia y flexibilidad sin precedentes.<\/p>\n\n<h2>El Poder de EIP-7702<\/h2>\n\n<p>La nueva funci\u00f3n est\u00e1 impulsada por EIP-7702, un est\u00e1ndar t\u00e9cnico en Ethereum que define ciertas reglas de mejoras para una mejor funcionalidad. Los usuarios de Bitget Wallet ahora pueden pagar el gas, la tarifa de transacci\u00f3n en Ethereum, en tres stablecoins diferentes: USDT, USDC o BGB. Esta innovadora caracter\u00edstica funciona sin problemas a trav\u00e9s de una multitud de redes blockchain, incluidas Ethereum, Solana, Base, TRON, Polygon, Arbitrum, BNB Chain y Optimism.<\/p>\n\n<p>Se informa que Bitget lanz\u00f3 esta caracter\u00edstica como parte de su iniciativa de &#8216;abstracci\u00f3n de gas&#8217;, un esfuerzo por simplificar el proceso de interacci\u00f3n con la red de Ethereum. La abstracci\u00f3n de gas permite a los usuarios pagar tarifas de transacci\u00f3n en tokens distintos de Ether, la criptomoneda nativa de Ethereum.<\/p>\n\n<h2>Funcionalidad de Billetera de Contrato Inteligente<\/h2>\n\n<p>Explicando la funcionalidad de EIP-7702, esta permite que una cuenta de propiedad externa (EOA) funcione temporalmente como una billetera de contrato inteligente. Esto otorga a la direcci\u00f3n capacidades tales como el procesamiento por lotes de transacciones y el patrocinio de gas. Aqu\u00ed, el procesamiento por lotes significa agrupar varias transacciones para ejecutarlas de una vez, mientras que el patrocinio de gas permite el pago de las tarifas de gas por parte de terceros.<\/p>\n\n<p>Jamie Elkaleh, Director de Marketing de Bitget Wallet, explic\u00f3 los beneficios de esta nueva funci\u00f3n: &#8216;Esto acerca la auto-custodia a la facilidad de los intercambios centralizados &#8211; los usuarios pueden transaccionar a trav\u00e9s de cadenas sin necesidad de gestionar tokens de gas.&#8217;<\/p>\n\n<h2>Integraci\u00f3n Integral entre Cadenas<\/h2>\n\n<p>Profundizando en los beneficios, Elkaleh se\u00f1al\u00f3 que la nueva integraci\u00f3n EIP de Bitget Wallet no solo funciona con ecosistemas de M\u00e1quina Virtual de Ethereum (EVM) sino incluso con aquellos que no son EVM, a diferencia de otras billeteras. Esta amplitud es exclusiva de Bitget Wallet, ya que otras plataformas requieren actualizaciones de cuenta inteligente o solo soportan la abstracci\u00f3n de gas en un n\u00famero limitado de cadenas.<\/p>\n\n<h2>Competencia en el Espacio de Billeteras de Criptomonedas<\/h2>\n\n<p>Con el lanzamiento de esta innovadora funci\u00f3n, Bitget Wallet est\u00e1 en competencia directa con nuevas soluciones e iniciativas que actualmente est\u00e1n siendo probadas por otras plataformas de criptomonedas, incluidas MetaMask, OKX Wallet y Base App. Estas plataformas tambi\u00e9n tienen como objetivo implementar la abstracci\u00f3n de gas e iniciativas de Paymaster, permitiendo a sus usuarios pagar tarifas de transacci\u00f3n en sus tokens deseados.<\/p>\n\n<h2>Descargo de Responsabilidad<\/h2>\n\n<p>The Block contin\u00faa operando de manera independiente para ofrecer informaci\u00f3n objetiva, impactante y oportuna sobre la industria de criptomonedas. Este art\u00edculo se proporciona solo con fines informativos. No se ofrece ni se pretende que se use como asesoramiento legal, fiscal, de inversi\u00f3n, financiero u otro tipo de asesoramiento. El intercambio de criptomonedas Bitget es un socio LP de Foresight Ventures, el principal inversor de The Block. Tambi\u00e9n tienen inversiones en otras compa\u00f1\u00edas del \u00e1mbito de las criptomonedas. Todos los derechos deben ser reservados a The Block a partir de 2025.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bitget Wallet ha introducido una actualizaci\u00f3n integrando la Propuesta de Mejora de Ethereum, EIP-7702, permitiendo a los usuarios pagar las comisiones de transacci\u00f3n con stablecoins como USDT, USDC o BGB. La nueva funci\u00f3n abarca tanto los ecosistemas EVM como los no EVM, facilitando las transacciones en m\u00faltiples cadenas y posicionando a Bitget Wallet en competencia directa con las iniciativas de abstracci\u00f3n de gas de plataformas rivales, incluyendo MetaMask, OKX Wallet y Base App.<\/p>\n","protected":false},"author":2802,"featured_media":70849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"category":[155,139],"tags":[],"posts_type":[122],"class_list":["post-70901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-cryptocurrency","posts_type-type_blog-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/posts\/70901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/users\/2802"}],"replies":[{"embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/comments?post=70901"}],"version-history":[{"count":1,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/posts\/70901\/revisions"}],"predecessor-version":[{"id":70902,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/posts\/70901\/revisions\/70902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/media\/70849"}],"wp:attachment":[{"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/media?parent=70901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/category?post=70901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/tags?post=70901"},{"taxonomy":"posts_type","embeddable":true,"href":"https:\/\/altsignals.io\/es\/wp-json\/wp\/v2\/posts_type?post=70901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}