{"id":137180,"date":"2026-09-02T08:11:47","date_gmt":"2026-09-02T08:11:47","guid":{"rendered":"https:\/\/altsignals.io\/result\/altsignals-io-actualizeai-acai-june-2026"},"modified":"2026-09-02T10:17:13","modified_gmt":"2026-09-02T10:17:13","slug":"altsignals-io-actualizeai-acai-june-2026","status":"publish","type":"reports","link":"https:\/\/altsignals.io\/ms\/result\/altsignals-io-actualizeai-acai-june-2026","title":{"rendered":"ActualizeAI (ACAI) June 2026"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"markets":[159],"class_list":["post-137180","reports","type-reports","status-publish","hentry","markets-actualizeai"],"acf":[],"_links":{"self":[{"href":"https:\/\/altsignals.io\/ms\/wp-json\/wp\/v2\/reports\/137180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altsignals.io\/ms\/wp-json\/wp\/v2\/reports"}],"about":[{"href":"https:\/\/altsignals.io\/ms\/wp-json\/wp\/v2\/types\/reports"}],"wp:attachment":[{"href":"https:\/\/altsignals.io\/ms\/wp-json\/wp\/v2\/media?parent=137180"}],"wp:term":[{"taxonomy":"markets","embeddable":true,"href":"https:\/\/altsignals.io\/ms\/wp-json\/wp\/v2\/markets?post=137180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}